{"id":706816,"date":"2026-05-12T16:16:02","date_gmt":"2026-05-12T15:16:02","guid":{"rendered":"https:\/\/blog.jetbrains.com\/?post_type=ai&#038;p=706816"},"modified":"2026-05-12T16:16:04","modified_gmt":"2026-05-12T15:16:04","slug":"donner-a-l-ia-quelque-chose-qui-merite-d-etre-amplifie-trois-priorites-pour-les-responsables-techniques","status":"publish","type":"ai","link":"https:\/\/blog.jetbrains.com\/fr\/ai\/2026\/05\/donner-a-l-ia-quelque-chose-qui-merite-d-etre-amplifie-trois-priorites-pour-les-responsables-techniques\/","title":{"rendered":"Donner \u00e0 l\u2019IA quelque chose qui m\u00e9rite d\u2019\u00eatre amplifi\u00e9 : trois priorit\u00e9s pour les responsables techniques"},"content":{"rendered":"<p>La plupart des organisations demandent ce que l&#8217;IA peut faire pour leurs d\u00e9veloppeurs. Une question plus complexe est : qu\u2019est-ce que vos d\u00e9veloppeurs apportent \u00e0 l\u2019IA ?<\/p>\n<p>Le <a href=\"https:\/\/cloud.google.com\/resources\/content\/2025-dora-ai-capabilities-model-report\" target=\"_blank\" rel=\"noopener\">rapport\u00a0<em>2025 sur le mod\u00e8le des capacit\u00e9s de l&#8217;IA<\/em><\/a> de\u00a0DORA soutient que l&#8217;IA ne nivelle pas les \u00e9quipes\u00a0; elle amplifie ce qu&#8217;elle y trouve. Les organisations les plus performantes en tirent davantage parti, tandis que les faiblesses des \u00e9quipes en difficult\u00e9 deviennent plus visibles.\u00a0<\/p>\n<p>Il semble qu&#8217;il en va de m\u00eame au niveau individuel. <a href=\"https:\/\/www.gitclear.com\/developer_ai_productivity_analysis_tools_research_2026\" target=\"_blank\" rel=\"noopener\">L&#8217;analyse de\u00a0GitClear de janvier\u00a02026<\/a> portant sur 2\u00a0172\u00a0semaines de d\u00e9veloppement a r\u00e9v\u00e9l\u00e9 que les utilisateurs r\u00e9guliers de l\u2019IA produisaient environ 320 % (4,2 fois) plus de code durable que les non-utilisateurs. Ces m\u00eames utilisateurs ont \u00e9galement augment\u00e9 leur production de 25 % entre 2024 et 2025. Il s\u2019agit d\u2019une am\u00e9lioration significative, mais qui n\u2019explique pas \u00e0 elle seule l\u2019ensemble de l\u2019\u00e9cart. La conclusion de GitClear est que l&#8217;IA a accentu\u00e9 une diff\u00e9rence de performance qui existait d\u00e9j\u00e0. Les ing\u00e9nieurs exp\u00e9riment\u00e9s et tr\u00e8s productifs ont souvent \u00e9t\u00e9 les premiers \u00e0 adopter l&#8217;IA.\u00a0\u00a0\u00a0<\/p>\n<p>Cela compte, car l&#8217;IA ne fonctionne pas dans le vide. Elle vient se superposer aux habitudes, syst\u00e8mes et contraintes d\u00e9j\u00e0 pr\u00e9sents dans votre \u00e9quipe. Si les fondations sont solides, l&#8217;IA peut aider. Si elles sont fragiles, l\u2019IA donne simplement plus d\u2019espace aux faiblesses pour se propager.\u00a0<\/p>\n<p>Certaines de ces fondations sont faciles \u00e0 voir. L&#8217;infrastructure apparait sur votre bilan et les outils peuvent \u00eatre inventori\u00e9s. Cet article se concentre sur trois domaines plus faciles \u00e0 n\u00e9gliger\u00a0: la r\u00e9vision du code, la dette technique et le jugement des d\u00e9veloppeurs. Ces probl\u00e8mes ne sont pas nouveaux, mais l\u2019IA les rend plus faciles \u00e0 ignorer tout en rendant leurs cons\u00e9quences plus difficiles \u00e0 \u00e9viter.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Priorit\u00e9 n\u00b0\u00a01\u00a0: renforcer la r\u00e9vision du code<\/strong><\/h2>\n<p>L&#8217;IA permet aux d\u00e9veloppeurs d&#8217;\u00e9crire plus de code plus vite, mais cela n&#8217;est utile que si le processus de r\u00e9vision peut g\u00e9rer le volume suppl\u00e9mentaire. Si le pipeline de r\u00e9vision est d\u00e9j\u00e0 sous pression, l&#8217;IA ne r\u00e9sout pas le probl\u00e8me\u00a0: elle envoie simplement plus de code dans le m\u00eame goulot d&#8217;\u00e9tranglement. Des lots de modifications plus importants arrivent plus rapidement, la responsabilit\u00e9 devient plus floue et les r\u00e9visions se limitent \u00e0 rep\u00e9rer les signaux d\u2019alerte \u00e9vidents au lieu de comprendre globalement les changements.<\/p>\n<p>Les donn\u00e9es le montrent d\u00e9j\u00e0. Le <a href=\"https:\/\/linearb.io\/resources\/software-engineering-benchmarks-report\" target=\"_blank\" rel=\"noopener\"><em>Rapport\u00a02026 sur les benchmarks en en ing\u00e9nierie logicielle<\/em><\/a> de\u00a0LinearB a constat\u00e9 que les pull requests contenant du code assist\u00e9 par IA attendaient environ 2,5\u00a0fois plus longtemps avant d&#8217;\u00eatre r\u00e9vis\u00e9es que celles \u00e9crites sans IA. Lorsque les agents d&#8217;IA avaient \u00e9crit le code de mani\u00e8re autonome, ce d\u00e9lai montait \u00e0 5,3 fois plus. Leur explication est simple\u00a0: les d\u00e9veloppeurs h\u00e9sitent \u00e0 prendre en charge une t\u00e2che de r\u00e9vision per\u00e7ue comme plus longue et plus risqu\u00e9e.\u00a0<\/p>\n<p>Le probl\u00e8me ne vient donc pas seulement du volume. C&#8217;est le volume combin\u00e9 \u00e0 l&#8217;incertitude, inject\u00e9 dans un processus qui n&#8217;a pas chang\u00e9.\u00a0<\/p>\n<p>C&#8217;est pourquoi la r\u00e9ponse r\u00e9side dans les processus, pas dans les effectifs.<\/p>\n<p><strong>Prochaines actions \u00e0 envisager :<\/strong><\/p>\n<ul>\n<li><strong>Mettre en place ou resserrer votre norme de taille de lot maximale pour les pull requests.<\/strong> DORA a d\u00e9termin\u00e9 que les petits lots formaient l&#8217;une des meilleures protections contre les pav\u00e9s de code difficiles \u00e0 r\u00e9viser, et l&#8217;IA facilite la cr\u00e9ation de ces pav\u00e9s.\u00a0<\/li>\n<\/ul>\n<ul>\n<li><strong>Faire de l&#8217;analyse statique une v\u00e9ritable barri\u00e8re, pas une suggestion.<\/strong> Les \u00e9valuations des r\u00e9viseurs ne permettent pas \u00e0 elles seules de distinguer de mani\u00e8re fiable les pull requests de haute qualit\u00e9 des autres. Une <a href=\"https:\/\/arxiv.org\/abs\/1908.09321\" target=\"_blank\" rel=\"noopener\">\u00e9tude de 2019<\/a> portant sur 4,7\u00a0millions de probl\u00e8mes de qualit\u00e9 du code dans 36\u00a0000\u00a0pull requests a montr\u00e9 que les pull requests accept\u00e9es et rejet\u00e9es se ressemblaient \u00e9tonnamment sur le plan des indicateurs de qualit\u00e9. Une \u00e9tude r\u00e9alis\u00e9e <a href=\"https:\/\/arxiv.org\/abs\/2601.21102\" target=\"_blank\" rel=\"noopener\">en janvier\u00a02026<\/a> a confirm\u00e9 ce sch\u00e9ma pour le code g\u00e9n\u00e9r\u00e9 par IA. L\u2019analyse statique r\u00e9duit la part de subjectivit\u00e9 dans la d\u00e9cision d\u2019accepter ou non une modification.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"><strong>Priorit\u00e9 n\u00b0\u00a02\u00a0: faire preuve de discipline en mati\u00e8re de dette technique\u00a0<\/strong><\/h2>\n<p>L&#8217;IA peut aider \u00e0 r\u00e9duire la dette technique existante, \u00e0 am\u00e9liorer la documentation, \u00e0 ajouter des tests et \u00e0 effectuer un nettoyage r\u00e9p\u00e9titif. Mais elle peut aussi faciliter l&#8217;accumulation d&#8217;une nouvelle dette plus rapidement que la base de code ne peut l&#8217;absorber. Trois s\u00e9ries de donn\u00e9es ind\u00e9pendantes vont dans ce m\u00eame sens.\u00a0<\/p>\n<ul>\n<li>L&#8217;<a href=\"https:\/\/www.gitclear.com\/ai_assistant_code_quality_2025_research\" target=\"_blank\" rel=\"noopener\">analyse longitudinale de\u00a0211\u00a0millions de lignes de code r\u00e9alis\u00e9e par\u00a0GitClear en\u00a02025<\/a> a r\u00e9v\u00e9l\u00e9 que le volume de modifications du code a augment\u00e9 de 84\u00a0% entre\u00a02020 et\u00a02024. La refactorisation a fortement chut\u00e9, passant de 25\u00a0% des lignes modifi\u00e9es en\u00a02021 \u00e0 moins de 10\u00a0% en\u00a02024. On trouve plus de 10\u00a0fois plus de blocs de code dupliqu\u00e9s en\u00a02024 qu&#8217;en\u00a02022. GitClear relie ces changements \u00e0 l&#8217;essor de la programmation assist\u00e9e par IA apr\u00e8s\u00a02022.<\/li>\n<li><a href=\"https:\/\/www.faros.ai\/ai-productivity-paradox\" target=\"_blank\" rel=\"noopener\">L&#8217;analyse de t\u00e9l\u00e9m\u00e9trie r\u00e9alis\u00e9e par Faros AI en 2025<\/a>, portant sur plus de 10\u00a0000\u00a0d\u00e9veloppeurs a r\u00e9v\u00e9l\u00e9 que les \u00e9quipes passant d&#8217;une faible adoption de l&#8217;IA \u00e0 une forte adoption de l&#8217;IA ont constat\u00e9 9\u00a0% de bugs suppl\u00e9mentaires par d\u00e9veloppeur, des pull requests d&#8217;une taille sup\u00e9rieure de 154\u00a0% en moyenne ainsi que des d\u00e9lais de r\u00e9vision allong\u00e9s de 91\u00a0%. La production individuelle a augment\u00e9, mais pas la performance organisationnelle.<\/li>\n<li>Une <a href=\"https:\/\/arxiv.org\/abs\/2511.04427\" target=\"_blank\" rel=\"noopener\">\u00e9tude r\u00e9alis\u00e9e en 2025 par Carnegie Mellon<\/a> a abouti \u00e0 des conclusions similaires. Les chercheurs ont suivi 806\u00a0\u00e9quipes ayant adopt\u00e9 un outil de programmation par IA et les ont compar\u00e9es \u00e0 1\u00a0380\u00a0\u00e9quipes qui ne l&#8217;avaient pas fait. Les avertissements de l&#8217;analyse statique ont augment\u00e9 d&#8217;environ 30\u00a0% apr\u00e8s l&#8217;adoption et sont rest\u00e9s \u00e9lev\u00e9s. La complexit\u00e9 cognitive a augment\u00e9 d&#8217;environ 41\u00a0% et est rest\u00e9e \u00e9lev\u00e9e, m\u00eame apr\u00e8s la prise en compte de la croissance de la base de code par les chercheurs. Le code n&#8217;\u00e9tait pas juste plus volumineux, il \u00e9tait aussi plus difficile \u00e0 comprendre.\u00a0<\/li>\n<\/ul>\n<p>Le sch\u00e9ma est difficile \u00e0 ignorer : la production augmente plus vite que les m\u00e9canismes de contr\u00f4le de la qualit\u00e9 qui l\u2019entourent.<\/p>\n<p>Cela n&#8217;implique pas que les \u00e9quipes ont besoin de moins d&#8217;IA. Cela signifie qu\u2019elles ont besoin de plus de discipline dans l\u2019allocation de leur temps.<\/p>\n<p><strong>Prochaines actions \u00e0 envisager :<\/strong><\/p>\n<ul>\n<li><strong>Prot\u00e9ger explicitement la capacit\u00e9 de sprint pour r\u00e9duire la dette technique. <\/strong>Si l&#8217;IA augmente la pression pour livrer rapidement, alors la refactorisation et l&#8217;analyse statique deviennent plus importantes, pas moins.<\/li>\n<\/ul>\n<ul>\n<li><strong>Cartographier les risques li\u00e9s aux connaissances avant que l&#8217;IA ne les aggrave.<\/strong> Demandez \u00e0 vos d\u00e9veloppeurs quelles parties du code ils h\u00e9siteraient \u00e0 modifier sans une longue phase d\u2019apprentissage. Utilisez ces informations pour prioriser la refactorisation, la documentation et la rotation volontaire des r\u00e9viseurs.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"><strong>Priorit\u00e9 n\u00b0\u00a03\u00a0: donner un terrain d&#8217;exp\u00e9rimentation au jugement des d\u00e9veloppeurs<\/strong><\/h2>\n<p>Une meilleure r\u00e9vision du code et une meilleure discipline en mati\u00e8re de dette technique d\u00e9pendent d&#8217;un \u00e9l\u00e9ment plus fondamental\u00a0: des personnes capables de r\u00e9ellement comprendre ce qu\u2019elles regardent. Cette comp\u00e9tence n&#8217;arrive pas automatiquement, et l&#8217;IA permet d&#8217;\u00e9viter plus facilement de la travailler.<\/p>\n<ul>\n<li><a href=\"https:\/\/arxiv.org\/abs\/2601.20245\" target=\"_blank\" rel=\"noopener\">L&#8217;essai contr\u00f4l\u00e9 randomis\u00e9 r\u00e9alis\u00e9 par Anthropic en janvier\u00a02026<\/a> rend ce risque concret. Les chercheurs ont r\u00e9parti des d\u00e9veloppeurs juniors apprenant une nouvelle biblioth\u00e8que Python en deux groupes, l\u2019un assist\u00e9 par IA, l\u2019autre codant manuellement. Les d\u00e9veloppeurs qui avaient d\u00e9l\u00e9gu\u00e9 la g\u00e9n\u00e9ration de code \u00e0 l&#8217;IA avant de passer \u00e0 autre chose ont obtenu un score compris entre 24\u00a0% et 39\u00a0% lors d&#8217;une \u00e9valuation ult\u00e9rieure de leur compr\u00e9hension. Les d\u00e9veloppeurs qui avaient utilis\u00e9 l&#8217;IA tout en d\u00e9veloppant activement leur compr\u00e9hension ont obtenu un score compris entre 65\u00a0% et 86\u00a0%. La conclusion d&#8217;Anthropic est sans d\u00e9tour\u00a0: \u00ab\u00a0Les gains de productivit\u00e9 peuvent se faire au d\u00e9triment des comp\u00e9tences n\u00e9cessaires pour valider le code \u00e9crit par l&#8217;IA\u00a0\u00bb.\u00a0\u00a0<\/li>\n<\/ul>\n<ul>\n<li>Le CTO d&#8217;Azure et vice-pr\u00e9sident de la communaut\u00e9 des d\u00e9veloppeurs de Microsoft a d\u00e9crit ce constat comme un <a href=\"https:\/\/dl.acm.org\/doi\/10.1145\/3779312\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0changement technologique biais\u00e9 par l\u2019anciennet\u00e9<\/a>\u00a0\u00bb.Les ing\u00e9nieurs seniors en b\u00e9n\u00e9ficient, car ils ont d\u00e9j\u00e0 le jugement n\u00e9cessaire pour orienter, v\u00e9rifier et int\u00e9grer les r\u00e9sultats de l&#8217;IA. C&#8217;est rarement le cas des ing\u00e9nieurs moins exp\u00e9riment\u00e9s. Pour eux, les m\u00eames outils peuvent devenir un frein plut\u00f4t qu\u2019un levier.<\/li>\n<\/ul>\n<p>Cela cr\u00e9e une logique tentante \u00e0 court terme\u00a0: embaucher des profils seniors, automatiser les t\u00e2ches confi\u00e9es aux juniors et passer \u00e0 autre chose. Cela peut sembler pertinent pendant un trimestre ou deux, mais cela risque aussi de vider le pipeline dont vous aurez besoin \u00e0 l&#8217;avenir. Le jugement qui rend l&#8217;IA utile doit \u00eatre d\u00e9velopp\u00e9 avant d&#8217;\u00eatre amplifi\u00e9.<\/p>\n<p><strong>Prochaines actions \u00e0 envisager :<\/strong><\/p>\n<ul>\n<li><strong>R\u00e9examiner votre strat\u00e9gie de recrutement junior sous l\u2019angle de la continuit\u00e9 m\u00e9tier.<\/strong> D&#8217;o\u00f9 viendront vos d\u00e9veloppeurs seniors dans quatre ans\u00a0? Une <a href=\"https:\/\/digitaleconomy.stanford.edu\/app\/uploads\/2025\/12\/CanariesintheCoalMine_Nov25.pdf\" target=\"_blank\" rel=\"noopener\">\u00e9tude de Stanford Digital Economy<\/a> de\u00a02025 a r\u00e9v\u00e9l\u00e9 une baisse relative de l&#8217;emploi de 16\u00a0% parmi les personnes \u00e2g\u00e9es de 22 \u00e0 25\u00a0ans dans les professions expos\u00e9es \u00e0 l&#8217;IA, m\u00eame apr\u00e8s la prise en comte des tendances d&#8217;embauche plus g\u00e9n\u00e9rales.<\/li>\n<\/ul>\n<ul>\n<li><strong>R\u00e9duire le d\u00e9ficit de mentorat cr\u00e9\u00e9 par l\u2019IA.<\/strong> <a href=\"https:\/\/leaddev.com\/the-ai-impact-report-2025\" target=\"_blank\" rel=\"noopener\"><em>Le rapport\u00a02025 sur l&#8217;impact de l&#8217;IA de LeadDev<\/em><\/a> a r\u00e9v\u00e9l\u00e9 que 38\u00a0% des responsables d&#8217;ing\u00e9nierie estimaient que les outils d&#8217;IA avaient r\u00e9duit le mentorat direct pour les ing\u00e9nieurs juniors. Ce transfert de connaissances ne se fait pas tout seul lorsque les deux parties ont un assistant d&#8217;IA sous la main.\u00a0<\/li>\n<\/ul>\n<ul>\n<li><strong>S\u00e9lectionner et int\u00e9grer les candidats en fonction de leur capacit\u00e9 de jugement de l&#8217;IA, et non pas seulement de leur connaissance des outils d&#8217;IA<\/strong>. La question n&#8217;est plus de savoir si quelqu&#8217;un utilise l&#8217;IA, mais s&#8217;il sait quand ne pas le faire.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"><strong>Remarque tactique\u00a0: d\u00e9finissez l&#8217;orientation, pas les outils<\/strong><\/h2>\n<p>La fa\u00e7on d&#8217;appliquer ces priorit\u00e9s a son importance. Les d\u00e9veloppeurs ressentiront la diff\u00e9rence entre le leadership et le contr\u00f4le. <a href=\"https:\/\/survey.stackoverflow.co\/2025\" target=\"_blank\" rel=\"noopener\"><em>L&#8217;enqu\u00eate\u00a02025 de Stack Overflow aupr\u00e8s des d\u00e9veloppeurs<\/em><\/a> a r\u00e9v\u00e9l\u00e9 que \u00ab\u00a0l&#8217;autonomie et la confiance\u00a0\u00bb \u00e9taient les principaux facteurs de satisfaction professionnelle des d\u00e9veloppeurs.<\/p>\n<p>On retrouve cette m\u00eame envie d&#8217;ind\u00e9pendance dans le choix des outils d&#8217;IA. Le <a href=\"https:\/\/www.harness.io\/event\/state-of-software-delivery\" target=\"_blank\" rel=\"noopener\"><em>rapport\u00a02025 sur l&#8217;\u00e9tat de la livraison de logiciels<\/em><\/a> de Harness a r\u00e9v\u00e9l\u00e9 que 52\u00a0% des d\u00e9veloppeurs n&#8217;utilisent pas les outils d&#8217;IA fournis par leur service informatique. Ce n&#8217;est probablement pas sur ce point qu&#8217;il faut tenter d&#8217;imposer une standardisation.<\/p>\n<p>N&#8217;imposez pas un choix de mod\u00e8le. N&#8217;imposez pas un assistant. Vos normes doivent concerner la couche d&#8217;acc\u00e8s.\u00a0<\/p>\n<h2 class=\"wp-block-heading\"><strong>Offrez \u00e0 votre \u00e9quipe un espace de travail compatible avec tous les outils d&#8217;IA<\/strong><\/h2>\n<p>Les JetBrains IDEs offrent \u00e0 vos d\u00e9veloppeurs un environnement coh\u00e9rent pour travailler avec pratiquement <a href=\"https:\/\/blog.jetbrains.com\/ai\/2025\/12\/bring-your-own-key-byok-is-now-live-in-jetbrains-ides\/\">n&#8217;importe quel LLM<\/a> ou agent de programmation <a href=\"https:\/\/www.jetbrains.com\/fr-fr\/acp\/\" target=\"_blank\" rel=\"noopener\">compatible avec l&#8217;ACP<\/a>. Cela leur permet d\u2019essayer de nouveaux outils sans avoir \u00e0 reconstruire leur workflow \u00e0 chaque \u00e9volution du march\u00e9.\u00a0<\/p>\n<p>Sous cette flexibilit\u00e9 se cache quelque chose de plus stable\u00a0: le mod\u00e8le structurel de l&#8217;IDE pour votre base de code. Il n&#8217;essaie pas de deviner pas ce que le code peut signifier. Il comprend r\u00e9ellement le code en tant que tel. Si l&#8217;IA g\u00e9n\u00e8re quelque chose de plausible mais qui casse quelque chose ailleurs, l&#8217;IDE peut le signaler avant que la modification arrive en r\u00e9vision. Ajoutez JetBrains Qodana, et ce m\u00eame mod\u00e8le structurel s&#8217;\u00e9tend \u00e0 l&#8217;analyse statique continue de l&#8217;ensemble de votre base de code.\u00a0\u00a0<\/p>\n<p>Le point essentiel, en pratique\u00a0: standardisez seulement que ce qui doit l&#8217;\u00eatre, et pr\u00e9servez la flexibilit\u00e9 pour le reste. Le All Products Pack s&#8217;inscrit dans la m\u00eame logique. Il inclut tous les IDE JetBrains dans un seul abonnement, chacun \u00e9tant con\u00e7u pour un langage majeur utilis\u00e9 aujourd\u2019hui ou n\u00e9cessaire demain. Lorsqu\u2019un d\u00e9veloppeur change de stack, il n\u2019y a ni demande de licence, ni d\u00e9lai d\u2019approvisionnement, ni nouveau cycle d\u2019approbation.\u00a0<\/p>\n<p>La d\u00e9cision est d\u00e9j\u00e0 prise. Les outils sont d\u00e9j\u00e0 l\u00e0.<\/p>\n<p><a href=\"https:\/\/www.jetbrains.com\/fr-fr\/business\/\" target=\"_blank\" rel=\"noopener\" data-type=\"link\" data-id=\"https:\/\/www.jetbrains.com\/business\/\">En savoir plus sur le All Products Pack.<\/a><\/p>\n<p><em>Auteur de l&#8217;article original en anglais<\/em> :<\/p>\n\n    <div class=\"about-author \">\n        <div class=\"about-author__box\">\n            <div class=\"row\">\n                <div class=\"about-author__box-img\">\n                    <img decoding=\"async\" src=\"https:\/\/secure.gravatar.com\/avatar\/e130eebba8ce28a1fd9e1b685b4218db?s=200&#038;r=g\" width=\"200\" height=\"200\" alt=\"Colette Des Georges\" loading=\"lazy\"  class=\"avatar avatar-200 wp-user-avatar wp-user-avatar-200 photo avatar-default\">\n                <\/div>\n                <div class=\"about-author__box-text\">\n                                            <h4>Colette Des Georges<\/h4>\n                                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"author":813,"featured_media":702647,"comment_status":"closed","ping_status":"closed","template":"","categories":[8899,3776],"tags":[8168],"cross-post-tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/ai\/706816"}],"collection":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/ai"}],"about":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/types\/ai"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/users\/813"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/comments?post=706816"}],"version-history":[{"count":4,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/ai\/706816\/revisions"}],"predecessor-version":[{"id":707014,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/ai\/706816\/revisions\/707014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/media\/702647"}],"wp:attachment":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/media?parent=706816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/categories?post=706816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/tags?post=706816"},{"taxonomy":"cross-post-tag","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/cross-post-tag?post=706816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}