{"id":391158,"date":"2023-09-26T09:29:55","date_gmt":"2023-09-26T08:29:55","guid":{"rendered":"https:\/\/blog.jetbrains.com\/?post_type=dotnet&#038;p=391158"},"modified":"2023-09-26T09:29:59","modified_gmt":"2023-09-26T08:29:59","slug":"rejoignez-nous-pour-l-evenement-jetbrains-gamedev-day-2023","status":"publish","type":"dotnet","link":"https:\/\/blog.jetbrains.com\/fr\/dotnet\/2023\/09\/26\/rejoignez-nous-pour-l-evenement-jetbrains-gamedev-day-2023\/","title":{"rendered":"Rejoignez-nous pour l&#8217;\u00e9v\u00e9nement JetBrains GameDev Day 2023"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-387440\" src=\"https:\/\/blog.jetbrains.com\/wp-content\/uploads\/2023\/09\/Blog-1280x720-1.jpg\" alt=\"\" width=\"1280\" height=\"720\" \/><\/figure>\n<p>L&#8217;\u00e9dition 2023 de JetBrains GameDev Day, notre \u00e9v\u00e9nement d\u00e9di\u00e9 au d\u00e9veloppement de jeux, aura lieu <strong>vendredi 13 octobre<\/strong>. Nous esp\u00e9rons que cela sera un jour de chance et que vous serez nombreux \u00e0 nous rejoindre !<\/p>\n<p>Cette ann\u00e9e, nous avons invit\u00e9 <strong>11 intervenants experts<\/strong> issus de la communaut\u00e9, qui animeront des sessions et des discussions sur diff\u00e9rents domaines du d\u00e9veloppement de jeux et partagerons des conseils de pro. Les sujets abord\u00e9s porteront notamment sur le playtesting, le CI\/CD, la pile technologique DOTS de Unity et le d\u00e9veloppement pour Apple Vision Pro.<\/p>\n<p><em>Veuillez noter que cet \u00e9v\u00e9nement se tiendra en anglais.<\/em><\/p>\n<p>Petite nouveaut\u00e9 de l&#8217;\u00e9dition 2023 : nous passons \u00e0 un format <strong>hybride<\/strong>. L&#8217;\u00e9v\u00e9nement aura lieu en ligne et pourra donc \u00eatre suivi \u00e0 distance, comme d&#8217;habitude, mais nous organisons aussi une diffusion du livestream suivie d&#8217;une soir\u00e9e \u00e0 Chypre.<\/p>\n<div class=\"buttons\">\n<div class=\"buttons__row\"><a class=\"btn\" href=\"http:\/\/lp.jetbrains.com\/gamedev-day-2023\/?utm_source=google&amp;utm_medium=conference&amp;utm_campaign=rider&amp;utm_content=blog\" target=\"\" rel=\"noopener\">Je m&#8217;inscris\u00a0!<\/a><\/div>\n<\/div>\n<h1 class=\"wp-block-heading\">Agenda<\/h1>\n<ul>\n<li><em>Scalable and Cloud-Native Mobile Game CI\/CD Environment Using Unity<\/em>, par Nemoto Tadashi.<\/li>\n<li><em>How To Stop Writing View-Classes for Unity UI<\/em>, par Dmitrii Ivashchenko.<\/li>\n<li><em>Empowering Non-Developers: Creating Editor Tools and Workflow Customizations in Unity<\/em>, par Ants Aare Alamaa<\/li>\n<li><em>Top 10 Unity Assets That Every Project Should Use<\/em>, par Oles Dibrivniy<\/li>\n<li><em>godot-playfab \u2013 A Godot Extension To Easily Integrate PlayFab, a Cloud-Based Backend as a Service<\/em>, par Johannes Ebner<\/li>\n<li><em>Insights on Testing Unreal Engine Support in Tools With Many Dependencies<\/em>, par Oleg Kuldyshev<\/li>\n<li><em>CI\/CD for Unreal Engine Games Using TeamCity<\/em>, par Daniel Gallo<\/li>\n<li><em>Introduction to Data-Oriented Design in Unity<\/em>, par Johnny Thompson<\/li>\n<li><em>How to Apply the Software Engineering Process to the Gamedev Process<\/em>, par Ryan L&#8217;Italien<\/li>\n<li><em>How Sprocket Games Achieved 10x Playtest Velocity for an Unreal Engine Game With Kotlin DSL, BuildGraph, and AWS<\/em>, par Nicolas Tittley<\/li>\n<li><em>Getting Started Developing for Apple Vision Pro with Unity<\/em>, par Dan Miller<\/li>\n<\/ul>\n<p>Vous pouvez choisir de suivre l&#8217;int\u00e9gralit\u00e9 des sessions ou certaines d&#8217;entre elles seulement, en fonction de votre disponibilit\u00e9 et des sujets qui vous int\u00e9ressent le plus. Nous esp\u00e9rons que vous appr\u00e9cierez ces pr\u00e9sentations et nous vous encourageons \u00e0 poser des questions\u00a0aux intervenants !<\/p>\n<p>Les sessions seront diffus\u00e9es en direct sur YouTube et leurs enregistrements seront disponibles apr\u00e8s l&#8217;\u00e9v\u00e9nement. En attendant, vous pouvez consulter les <a href=\"https:\/\/pages.jetbrains.com\/dotnet-days-2022\" target=\"_blank\" rel=\"noopener\">enregistrements des sessions de l&#8217;ann\u00e9e derni\u00e8re<\/a>.<\/p>\n<p>Nous invitons aussi les <strong>groupes d&#8217;utilisateurs et entreprises de la communaut\u00e9 \u00e0 nous aider<\/strong> \u00e0 promouvoir cet \u00e9v\u00e9nement. Pour plus d&#8217;informations \u00e0 ce sujet, cliquez <a href=\"https:\/\/lp.jetbrains.com\/gamedev-day-2023-partners\/?utm_source=google&amp;utm_medium=conference&amp;utm_campaign=rider&amp;utm_content=blog\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<p>Vous pouvez consulter la pr\u00e9sentation et le programme complets de l&#8217;\u00e9v\u00e9nement <a href=\"https:\/\/jb.gg\/6lloi5\" target=\"_blank\" rel=\"noopener\">ici<\/a>. Nous avons h\u00e2te de vous retrouver en octobre\u00a0!<\/p>\n<p><em>Auteur de l&#8217;article original en anglais<\/em> :<\/p>\n\n    <div class=\"about-author \">\n        <div class=\"about-author__box\">\n            <div class=\"row\">\n                <div class=\"about-author__box-img\">\n                    <img decoding=\"async\" src=\"https:\/\/secure.gravatar.com\/avatar\/?s=200&#038;r=g\" width=\"200\" height=\"200\" alt=\"\" loading=\"lazy\"  class=\"avatar avatar-200 wp-user-avatar wp-user-avatar-200 photo avatar-default\">\n                <\/div>\n                <div class=\"about-author__box-text\">\n                                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"author":813,"featured_media":387451,"comment_status":"closed","ping_status":"closed","template":"","categories":[10,4918,4140],"tags":[181,652,1978,72,1941,2095],"cross-post-tag":[6256],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/dotnet\/391158"}],"collection":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/dotnet"}],"about":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/types\/dotnet"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/users\/813"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/comments?post=391158"}],"version-history":[{"count":11,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/dotnet\/391158\/revisions"}],"predecessor-version":[{"id":393086,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/dotnet\/391158\/revisions\/393086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/media\/387451"}],"wp:attachment":[{"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/media?parent=391158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/categories?post=391158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/tags?post=391158"},{"taxonomy":"cross-post-tag","embeddable":true,"href":"https:\/\/blog.jetbrains.com\/fr\/wp-json\/wp\/v2\/cross-post-tag?post=391158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}